{"id":2421,"date":"2026-02-10T13:38:45","date_gmt":"2026-02-10T12:38:45","guid":{"rendered":"https:\/\/maxilofacialchile.cl\/web\/?post_type=tribe_events&#038;p=2421"},"modified":"2026-02-10T13:51:40","modified_gmt":"2026-02-10T12:51:40","slug":"jornadas-multidisciplinarias-innovaciones-tecnologicas-en-el-diagnostico-y-tratamiento-de-los-trastornos-del-sueno","status":"publish","type":"tribe_events","link":"https:\/\/maxilofacialchile.cl\/web\/event\/jornadas-multidisciplinarias-innovaciones-tecnologicas-en-el-diagnostico-y-tratamiento-de-los-trastornos-del-sueno\/","title":{"rendered":"Jornadas Multidisciplinarias: Innovaciones Tecnol\u00f3gicas en el Diagn\u00f3stico y Tratamiento de los Trastornos del Sue\u00f1o"},"content":{"rendered":"<ul>\n<li><strong>Fecha:<\/strong> viernes 13 de marzo 2026.&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n<li><strong>Horario:<\/strong>&nbsp; 08:30 a 18:00 horas<\/li>\n<li><strong>Lugar<\/strong>: Cl\u00ednica Las Condes &#8211; Campus Estoril<\/li>\n<li><strong>Modalidad<\/strong>: Presencial<\/li>\n<li><strong>Valor del Curso<\/strong>:&nbsp; $ 30.000.<\/li>\n<\/ul>\n<p><strong>Dirigido<\/strong>: Profesionales de la salud que se desempe\u00f1en en trastornos del sue\u00f1o incluyendo m\u00e9dicos generales, internistas, broncopulmonares, neur\u00f3logos, pediatras, otorrinolaring\u00f3logos, psiquiatras, nutri\u00f3logos, geriatras , odont\u00f3logos, psic\u00f3logos, kinesi\u00f3logos y fonoaudi\u00f3logos con el fin de actualizar conocimientos y fortalecer competencias cl\u00ednicas en estas patolog\u00edas.<\/p>\n<p><strong>Directores:<\/strong><\/p>\n<p>Dra. Evelyn Benavides<br \/>\nKlga. Montserrat S\u00e1nchez<br \/>\nDr. Jorge Jorquera<\/p>\n<a  itemprop=\"url\" href=\"http:\/\/maxilofacialchile.cl\/web\/wp-content\/uploads\/2026\/02\/V6-Jornada_Innovacion_tecnologica_Centro_del_Sueno-ultimo.pdf\" target=\"_blank\"  class=\"qbutton  default\" style=\"\">Ver PDF programa<i class=\"qode_icon_font_awesome fa fa-arrow-right qode_button_icon_element\" style=\"\" ><\/i><\/a>\n<a  itemprop=\"url\" href=\"https:\/\/www.maxilofacialchile.cl\/web\/procesar\/servicios\" target=\"_self\"  class=\"qbutton  default\" style=\"\">Inscripci\u00f3n curso aqu\u00ed<i class=\"qode_icon_font_awesome fa fa-arrow-right qode_button_icon_element\" style=\"\" ><\/i><\/a>\n<p>&nbsp;<\/p>\n<hr>\n<h3>Invitados internacionales:<\/h3>\n<p><strong>Dr. Geraldo Lorenzi -Filho<\/strong><br \/>\nM\u00e9dico Neum\u00f3logo especialista en Medicina del Sue\u00f1o<br \/>\nPostdoctorado en el \u00e1rea de Medicina del Sue\u00f1o por la Universidad de Toronto<br \/>\nProfesor Titular por la Facultad de Medicina de la Universidad Sao Pablo<br \/>\nDirector del Laboratorio del Sue\u00f1o de la Disciplina de Neumolog\u00eda, InCor, HC &#8211; Facultad de Medicina de la Universidad Sao Pablo<br \/>\nPresidente de la Asociaci\u00f3n Brasile\u00f1a del Sue\u00f1o 2013-2015 y Vicepresidente 2015-2017<br \/>\nDirector del N\u00facleo Interdisciplinario de Ciencia del Sue\u00f1o<\/p>\n<p><strong>Flga. Vanessa Ieto<\/strong><br \/>\nLicenciatura y Maestr\u00eda en Fonoaudiolog\u00eda<br \/>\npor la Pontificia Universidad Cat\u00f3lica de<br \/>\nS\u00e3o Paulo (PUC-SP),<br \/>\nEspecializaci\u00f3n en Motricidad Orofacial<br \/>\npor el CEFAC<br \/>\nDoctorado por la Facultad de Medicina de la<br \/>\nUniversidad de S\u00e3o Paulo (FMUSP)<br \/>\nCoordinadora del curso multiprofesional de<br \/>\nformaci\u00f3n en sue\u00f1o del N\u00facleo<br \/>\nInterdisciplinario de Ciencia del Sue\u00f1o (NICS).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fecha: viernes 13 de marzo 2026.\u00a0\u00a0\u00a0\u00a0<br \/>\nHorario:\u00a0 08:30 a 18:00 horas<br \/>\nLugar: Cl\u00ednica Las Condes &#8211; Campus Estoril<br \/>\nModalidad: Presencial<br \/>\nValor del Curso:\u00a0 $ 30.000.<\/p>\n<p>Dirigido: Profesionales de la salud que se desempe\u00f1en en trastornos del sue\u00f1o incluyendo m\u00e9dicos generales, internistas, broncopulmonares, neur\u00f3logos, pediatras, otorrinolaring\u00f3logos, psiquiatras, nutri\u00f3logos, geriatras , odont\u00f3logos, psic\u00f3logos, kinesi\u00f3logos y fonoaudi\u00f3logos con el fin de actualizar conocimientos y fortalecer competencias cl\u00ednicas en estas patolog\u00edas.<\/p>\n<p>Directores:<br \/>\nDra. Evelyn Benavides<br \/>\nKlga. Montserrat S\u00e1nchez<br \/>\nDr. Jorge Jorquera<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"ngg_post_thumbnail":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[41],"class_list":["post-2421","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-cursos-y-congresos","cat_cursos-y-congresos"],"_links":{"self":[{"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tribe_events\/2421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tribe_events\/2421\/revisions"}],"predecessor-version":[{"id":2430,"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tribe_events\/2421\/revisions\/2430"}],"wp:attachment":[{"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/media?parent=2421"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tags?post=2421"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/maxilofacialchile.cl\/web\/wp-json\/wp\/v2\/tribe_events_cat?post=2421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}